{"id":1342,"date":"2023-06-18T11:39:00","date_gmt":"2023-06-18T11:39:00","guid":{"rendered":"https:\/\/blog.nitteknalogik.net\/?p=1342"},"modified":"2025-10-27T20:53:52","modified_gmt":"2025-10-27T20:53:52","slug":"la-ville-en-mouvment-rencontres-performatives-4eme-edition-2023","status":"publish","type":"post","link":"https:\/\/blog.nitteknalogik.net\/es\/la-ville-en-mouvment-rencontres-performatives-4eme-edition-2023\/","title":{"rendered":"&#8220;La ville en mouv&#8217;ment&#8221; Encuentros performativos 4\u00aa edici\u00f3n (2023)"},"content":{"rendered":"\n<p>&#8220;La Ville en Mouv&#8217;ment&#8221; es una serie de colaboraciones interdisciplinarias entre artistas senegaleses e internacionales para llevar el arte performativo contempor\u00e1neo a los espacios p\u00fablicos. Durante programas intensivos de una o dos semanas en Dakar y sus suburbios.<\/p>\n\n\n\n<p>Muchos artistas siempre se han expresado a trav\u00e9s de investigaciones, as\u00ed como de acciones concretas en respuesta a emergencias. Este programa, en marcha desde hace 4 a\u00f1os, invitar\u00e1 a artistas de performance, de las artes visuales y esc\u00e9nicas a colaborar durante 2 semanas de trabajo y creaci\u00f3n. Los artistas reciclar\u00e1n, transformar\u00e1n y acondicionar\u00e1n, proponiendo instalaciones en barrios marginales.<\/p>\n\n\n\n<p>El arte callejero utiliza un enfoque art\u00edstico y social para dar un nuevo impulso a determinadas zonas de la ciudad. Artes que invierten espacios en los que cada d\u00eda se forman relaciones e intercambios sociales. Diferentes conceptos ser\u00e1n abordado\u015b por siete equipos de artistas (7 proyectos). En las tres primeras ediciones, las calles se convirtieron en tel\u00f3n de fondo de actuaciones al aire libre e instalaciones multidisciplinares que galvanizaron a un p\u00fablico improvisado y desprevenido. La est\u00e9tica vanguardista combinada con referencias a actividades cotidianas enganch\u00f3 estrat\u00e9gicamente al p\u00fablico, propiciando conversaciones en profundidad, reflexiones y un mayor aprecio por parte de personas sin exposici\u00f3n previa a la performance contempor\u00e1nea.<\/p>\n\n\n\n<p>Este a\u00f1o asistimos a los encuentros, he aqu\u00ed un v\u00eddeo resumen.<\/p>\n\n\n\n<iframe loading=\"lazy\" title=\"Vid\u00e9o r\u00e9sum\u00e9 de la 4eme \u00e9dition La ville en mouv'ment - Rencontres performatives Dakar 2023\" width=\"560\" height=\"315\" src=\"https:\/\/peertube.iriseden.eu\/videos\/embed\/97fb4d9f-2c7f-4bc4-9f48-4f9354a9aaf4\" frameborder=\"0\" allowfullscreen=\"\" sandbox=\"allow-same-origin allow-scripts allow-popups\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La Ville en Mouv&#8217;ment&#8221; es una serie de colaboraciones interdisciplinarias entre artistas senegaleses e internacionales para llevar el arte performativo contempor\u00e1neo a los espacios p\u00fablicos. Durante programas intensivos de una o dos semanas en Dakar y sus suburbios. Muchos artistas siempre se han expresado a trav\u00e9s de investigaciones, as\u00ed como de acciones concretas en respuesta a emergencias. Este programa, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17,29],"tags":[],"class_list":["post-1342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiences","category-art"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["fr","en","es"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"jetpack_featured_media_url":"https:\/\/blog.nitteknalogik.net\/wp-content\/uploads\/2024\/03\/afficheLVNM2023.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/posts\/1342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/comments?post=1342"}],"version-history":[{"count":7,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/posts\/1342\/revisions"}],"predecessor-version":[{"id":1354,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/posts\/1342\/revisions\/1354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/media\/1343"}],"wp:attachment":[{"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/media?parent=1342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/categories?post=1342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.nitteknalogik.net\/es\/wp-json\/wp\/v2\/tags?post=1342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}